{"id":13535,"date":"2024-01-26T12:09:43","date_gmt":"2024-01-26T11:09:43","guid":{"rendered":"https:\/\/www.lesarmures.ch\/chambres\/chambre-superieure\/"},"modified":"2024-03-15T13:21:31","modified_gmt":"2024-03-15T12:21:31","slug":"chambre-superieure","status":"publish","type":"larm_room","link":"https:\/\/www.lesarmures.ch\/ar\/chambres\/chambre-superieure\/","title":{"rendered":"\u063a\u0631\u0641\u0629 \u0633\u0648\u0628\u064a\u0631\u064a\u0648\u0631"},"content":{"rendered":"<p>Dans une ambiance douce et coquette, ces chambres proposent un espace\u00a0<strong>chaleureux et raffin\u00e9<\/strong>. On y retrouve les vieilles pierres et le bois qui y c\u00f4toient des \u00e9quipements contemporains.<\/p>\n<p><strong>Ces chambres\u00a0<\/strong>sont \u00e9quip\u00e9es d\u2019un lit simple et d\u2019une baignoire.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u062a\u0642\u062f\u0645 \u0647\u0630\u0647 \u0627\u0644\u063a\u0631\u0641 \u0623\u0645\u0627\u0643\u0646 \u062f\u0627\u0641\u0626\u0629 \u0648\u0623\u0646\u064a\u0642\u0629 \u0644\u0625\u0642\u0627\u0645\u0629 \u0641\u064a \u0623\u062c\u0648\u0627\u0621 \u0631\u062e\u064a\u0629 \u0648\u0632\u0627\u0647\u0631\u0629. \u0648\u0646\u062c\u062f \u0641\u064a\u0647\u0627 \u0627\u0644\u062d\u062c\u0631 \u0627\u0644\u0642\u062f\u064a\u0645 \u0648\u0627\u0644\u062e\u0634\u0628 \u0627\u0644\u0645\u062a\u0646\u0627\u063a\u0645 \u0645\u0639 \u0627\u0644\u0623\u062c\u0647\u0632\u0629 \u0627\u0644\u062d\u062f\u064a\u062b\u0629. \u0648\u0647\u0630\u0647 \u0627\u0644\u063a\u0631\u0641 \u0645\u064f\u062c\u0647\u0651\u0632\u0629 \u0628\u0633\u0631\u064a\u0631 \u0641\u0631\u062f\u064a \u0648\u0645\u063a\u0637\u0633.<\/p>\n","protected":false},"featured_media":13536,"template":"","class_list":["post-13535","larm_room","type-larm_room","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u063a\u0631\u0641\u0629 \u0633\u0648\u0628\u064a\u0631\u064a\u0648\u0631 - Hotel Les Armures Gen\u00e8ve<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lesarmures.ch\/ar\/chambres\/chambre-superieure\/\" \/>\n<meta property=\"og:locale\" content=\"ar_AR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u063a\u0631\u0641\u0629 \u0633\u0648\u0628\u064a\u0631\u064a\u0648\u0631 - Hotel Les Armures Gen\u00e8ve\" \/>\n<meta property=\"og:description\" content=\"\u062a\u0642\u062f\u0645 \u0647\u0630\u0647 \u0627\u0644\u063a\u0631\u0641 \u0623\u0645\u0627\u0643\u0646 \u062f\u0627\u0641\u0626\u0629 \u0648\u0623\u0646\u064a\u0642\u0629 \u0644\u0625\u0642\u0627\u0645\u0629 \u0641\u064a \u0623\u062c\u0648\u0627\u0621 \u0631\u062e\u064a\u0629 \u0648\u0632\u0627\u0647\u0631\u0629. \u0648\u0646\u062c\u062f \u0641\u064a\u0647\u0627 \u0627\u0644\u062d\u062c\u0631 \u0627\u0644\u0642\u062f\u064a\u0645 \u0648\u0627\u0644\u062e\u0634\u0628 \u0627\u0644\u0645\u062a\u0646\u0627\u063a\u0645 \u0645\u0639 \u0627\u0644\u0623\u062c\u0647\u0632\u0629 \u0627\u0644\u062d\u062f\u064a\u062b\u0629. \u0648\u0647\u0630\u0647 \u0627\u0644\u063a\u0631\u0641 \u0645\u064f\u062c\u0647\u0651\u0632\u0629 \u0628\u0633\u0631\u064a\u0631 \u0641\u0631\u062f\u064a \u0648\u0645\u063a\u0637\u0633.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lesarmures.ch\/ar\/chambres\/chambre-superieure\/\" \/>\n<meta property=\"og:site_name\" content=\"Hotel Les Armures Gen\u00e8ve\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-15T12:21:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lesarmures.ch\/wp-content\/uploads\/2024\/01\/304-1-1024x683-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u0648\u0642\u062a \u0627\u0644\u0642\u0631\u0627\u0621\u0629 \u0627\u0644\u0645\u064f\u0642\u062f\u0651\u0631\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 \u062f\u0642\u064a\u0642\u0629\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lesarmures.ch\\\/ar\\\/chambres\\\/chambre-superieure\\\/\",\"url\":\"https:\\\/\\\/www.lesarmures.ch\\\/ar\\\/chambres\\\/chambre-superieure\\\/\",\"name\":\"\u063a\u0631\u0641\u0629 \u0633\u0648\u0628\u064a\u0631\u064a\u0648\u0631 - Hotel Les Armures Gen\u00e8ve\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lesarmures.ch\\\/ru\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lesarmures.ch\\\/ar\\\/chambres\\\/chambre-superieure\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesarmures.ch\\\/ar\\\/chambres\\\/chambre-superieure\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lesarmures.ch\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/304-1-1024x683-1.jpg\",\"datePublished\":\"2024-01-26T11:09:43+00:00\",\"dateModified\":\"2024-03-15T12:21:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lesarmures.ch\\\/ar\\\/chambres\\\/chambre-superieure\\\/#breadcrumb\"},\"inLanguage\":\"ar\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lesarmures.ch\\\/ar\\\/chambres\\\/chambre-superieure\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\\\/\\\/www.lesarmures.ch\\\/ar\\\/chambres\\\/chambre-superieure\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.lesarmures.ch\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/304-1-1024x683-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.lesarmures.ch\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/304-1-1024x683-1.jpg\",\"width\":1024,\"height\":683},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lesarmures.ch\\\/ar\\\/chambres\\\/chambre-superieure\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.lesarmures.ch\\\/ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u063a\u0631\u0641\u0629 \u0633\u0648\u0628\u064a\u0631\u064a\u0648\u0631\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lesarmures.ch\\\/ru\\\/#website\",\"url\":\"https:\\\/\\\/www.lesarmures.ch\\\/ru\\\/\",\"name\":\"Les Armures : H\u00f4tel 5 \u00e9toiles et restaurant \u00e0 Gen\u00e8ve\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.lesarmures.ch\\\/ru\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lesarmures.ch\\\/ru\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ar\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.lesarmures.ch\\\/ru\\\/#organization\",\"name\":\"Les Armures : H\u00f4tel 5 \u00e9toiles et restaurant \u00e0 Gen\u00e8ve\",\"url\":\"https:\\\/\\\/www.lesarmures.ch\\\/ru\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\\\/\\\/www.lesarmures.ch\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.lesarmures.ch\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/logo_alt_retina.png\",\"contentUrl\":\"https:\\\/\\\/www.lesarmures.ch\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/logo_alt_retina.png\",\"width\":726,\"height\":169,\"caption\":\"Les Armures : H\u00f4tel 5 \u00e9toiles et restaurant \u00e0 Gen\u00e8ve\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesarmures.ch\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u063a\u0631\u0641\u0629 \u0633\u0648\u0628\u064a\u0631\u064a\u0648\u0631 - Hotel Les Armures Gen\u00e8ve","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lesarmures.ch\/ar\/chambres\/chambre-superieure\/","og_locale":"ar_AR","og_type":"article","og_title":"\u063a\u0631\u0641\u0629 \u0633\u0648\u0628\u064a\u0631\u064a\u0648\u0631 - Hotel Les Armures Gen\u00e8ve","og_description":"\u062a\u0642\u062f\u0645 \u0647\u0630\u0647 \u0627\u0644\u063a\u0631\u0641 \u0623\u0645\u0627\u0643\u0646 \u062f\u0627\u0641\u0626\u0629 \u0648\u0623\u0646\u064a\u0642\u0629 \u0644\u0625\u0642\u0627\u0645\u0629 \u0641\u064a \u0623\u062c\u0648\u0627\u0621 \u0631\u062e\u064a\u0629 \u0648\u0632\u0627\u0647\u0631\u0629. \u0648\u0646\u062c\u062f \u0641\u064a\u0647\u0627 \u0627\u0644\u062d\u062c\u0631 \u0627\u0644\u0642\u062f\u064a\u0645 \u0648\u0627\u0644\u062e\u0634\u0628 \u0627\u0644\u0645\u062a\u0646\u0627\u063a\u0645 \u0645\u0639 \u0627\u0644\u0623\u062c\u0647\u0632\u0629 \u0627\u0644\u062d\u062f\u064a\u062b\u0629. \u0648\u0647\u0630\u0647 \u0627\u0644\u063a\u0631\u0641 \u0645\u064f\u062c\u0647\u0651\u0632\u0629 \u0628\u0633\u0631\u064a\u0631 \u0641\u0631\u062f\u064a \u0648\u0645\u063a\u0637\u0633.","og_url":"https:\/\/www.lesarmures.ch\/ar\/chambres\/chambre-superieure\/","og_site_name":"Hotel Les Armures Gen\u00e8ve","article_modified_time":"2024-03-15T12:21:31+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/www.lesarmures.ch\/wp-content\/uploads\/2024\/01\/304-1-1024x683-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"\u0648\u0642\u062a \u0627\u0644\u0642\u0631\u0627\u0621\u0629 \u0627\u0644\u0645\u064f\u0642\u062f\u0651\u0631":"1 \u062f\u0642\u064a\u0642\u0629"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.lesarmures.ch\/ar\/chambres\/chambre-superieure\/","url":"https:\/\/www.lesarmures.ch\/ar\/chambres\/chambre-superieure\/","name":"\u063a\u0631\u0641\u0629 \u0633\u0648\u0628\u064a\u0631\u064a\u0648\u0631 - Hotel Les Armures Gen\u00e8ve","isPartOf":{"@id":"https:\/\/www.lesarmures.ch\/ru\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lesarmures.ch\/ar\/chambres\/chambre-superieure\/#primaryimage"},"image":{"@id":"https:\/\/www.lesarmures.ch\/ar\/chambres\/chambre-superieure\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lesarmures.ch\/wp-content\/uploads\/2024\/01\/304-1-1024x683-1.jpg","datePublished":"2024-01-26T11:09:43+00:00","dateModified":"2024-03-15T12:21:31+00:00","breadcrumb":{"@id":"https:\/\/www.lesarmures.ch\/ar\/chambres\/chambre-superieure\/#breadcrumb"},"inLanguage":"ar","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lesarmures.ch\/ar\/chambres\/chambre-superieure\/"]}]},{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/www.lesarmures.ch\/ar\/chambres\/chambre-superieure\/#primaryimage","url":"https:\/\/www.lesarmures.ch\/wp-content\/uploads\/2024\/01\/304-1-1024x683-1.jpg","contentUrl":"https:\/\/www.lesarmures.ch\/wp-content\/uploads\/2024\/01\/304-1-1024x683-1.jpg","width":1024,"height":683},{"@type":"BreadcrumbList","@id":"https:\/\/www.lesarmures.ch\/ar\/chambres\/chambre-superieure\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.lesarmures.ch\/ar\/"},{"@type":"ListItem","position":2,"name":"\u063a\u0631\u0641\u0629 \u0633\u0648\u0628\u064a\u0631\u064a\u0648\u0631"}]},{"@type":"WebSite","@id":"https:\/\/www.lesarmures.ch\/ru\/#website","url":"https:\/\/www.lesarmures.ch\/ru\/","name":"Les Armures : H\u00f4tel 5 \u00e9toiles et restaurant \u00e0 Gen\u00e8ve","description":"","publisher":{"@id":"https:\/\/www.lesarmures.ch\/ru\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lesarmures.ch\/ru\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ar"},{"@type":"Organization","@id":"https:\/\/www.lesarmures.ch\/ru\/#organization","name":"Les Armures : H\u00f4tel 5 \u00e9toiles et restaurant \u00e0 Gen\u00e8ve","url":"https:\/\/www.lesarmures.ch\/ru\/","logo":{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/www.lesarmures.ch\/ru\/#\/schema\/logo\/image\/","url":"https:\/\/www.lesarmures.ch\/wp-content\/uploads\/2024\/01\/logo_alt_retina.png","contentUrl":"https:\/\/www.lesarmures.ch\/wp-content\/uploads\/2024\/01\/logo_alt_retina.png","width":726,"height":169,"caption":"Les Armures : H\u00f4tel 5 \u00e9toiles et restaurant \u00e0 Gen\u00e8ve"},"image":{"@id":"https:\/\/www.lesarmures.ch\/ru\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.lesarmures.ch\/ar\/wp-json\/wp\/v2\/larm_room\/13535","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lesarmures.ch\/ar\/wp-json\/wp\/v2\/larm_room"}],"about":[{"href":"https:\/\/www.lesarmures.ch\/ar\/wp-json\/wp\/v2\/types\/larm_room"}],"version-history":[{"count":3,"href":"https:\/\/www.lesarmures.ch\/ar\/wp-json\/wp\/v2\/larm_room\/13535\/revisions"}],"predecessor-version":[{"id":15773,"href":"https:\/\/www.lesarmures.ch\/ar\/wp-json\/wp\/v2\/larm_room\/13535\/revisions\/15773"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lesarmures.ch\/ar\/wp-json\/wp\/v2\/media\/13536"}],"wp:attachment":[{"href":"https:\/\/www.lesarmures.ch\/ar\/wp-json\/wp\/v2\/media?parent=13535"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}